{"id":556,"date":"2025-12-15T10:45:07","date_gmt":"2025-12-15T09:45:07","guid":{"rendered":"http:\/\/neuesmitteldeutschland.test\/?p=556"},"modified":"2026-04-28T16:55:02","modified_gmt":"2026-04-28T14:55:02","slug":"club-kino-glauchau","status":"publish","type":"post","link":"https:\/\/www.neues-mitteldeutschland.de\/index.php\/2025\/12\/15\/club-kino-glauchau\/","title":{"rendered":"Club-Kino Glauchau"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"556\" class=\"elementor elementor-556\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1827287 e-flex e-con-boxed e-con e-parent\" data-id=\"1827287\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-982ff12 e-con-full e-flex e-con e-child\" data-id=\"982ff12\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1accdf9 elementor-widget elementor-widget-html\" data-id=\"1accdf9\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t<table>\n    <tr>\n        <td>Anschrift:<\/td>\n        <td>Clubkino Glauchau e.V.<br>\n            Marienstrasse 46<br>\n            08371 Glauchau<\/td>\n    <\/tr>\n    <tr>\n        <td>Website:<\/td>\n        <td><a href=\"https:\/\/clubkino-glauchau.de\/\">Hier Klicken<\/a><\/td>\n    <\/tr>\n    <tr>\n        <td>Telefon:<\/td>\n        <td>03763 172975 <\/td>\n    <\/tr>\n    <tr>\n        <td>E-Mail:<\/td>\n        <td>info@clubkino-glauchau.de <\/td>\n    <\/tr>\n    <tr>\n        <td colspan=\"2\" align=\"center\"><u>Programm:<\/u>\n        <br>folgt...\n        <\/td>\n    <\/tr>\n<\/table>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-760707b e-con-full e-flex e-con e-child\" data-id=\"760707b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-99aa09a elementor-widget elementor-widget-google_maps\" data-id=\"99aa09a\" data-element_type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=Marienstrasse%2046%2C%20glauchau&#038;t=m&#038;z=10&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"Marienstrasse 46, glauchau\"\n\t\t\t\t\taria-label=\"Marienstrasse 46, glauchau\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8550427 e-flex e-con-boxed e-con e-parent\" data-id=\"8550427\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3e7b94f elementor-widget elementor-widget-image\" data-id=\"3e7b94f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1920\" height=\"721\" src=\"https:\/\/neues-mitteldeutschland.de\/wp-content\/uploads\/2025\/12\/kino-richtig.jpg\" class=\"attachment-full size-full wp-image-1444\" alt=\"\" srcset=\"https:\/\/neues-mitteldeutschland.de\/wp-content\/uploads\/2025\/12\/kino-richtig.jpg 1920w, https:\/\/neues-mitteldeutschland.de\/wp-content\/uploads\/2025\/12\/kino-richtig-300x113.jpg 300w, https:\/\/neues-mitteldeutschland.de\/wp-content\/uploads\/2025\/12\/kino-richtig-1024x385.jpg 1024w, https:\/\/neues-mitteldeutschland.de\/wp-content\/uploads\/2025\/12\/kino-richtig-768x288.jpg 768w, https:\/\/neues-mitteldeutschland.de\/wp-content\/uploads\/2025\/12\/kino-richtig-1536x577.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e7e9e4 elementor-widget elementor-widget-heading\" data-id=\"3e7e9e4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00dcber Uns<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a109990 elementor-widget elementor-widget-text-editor\" data-id=\"a109990\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-size: 16px;\">Der Verein Clubkino Glauchau e.V. besteht mittlerweile im 7. Jahr. Wer h\u00e4tte 2005, einschlie\u00dflich der Macher, gedacht, dass es uns so lange gibt. Damals suchte die Stadtverwaltung Glauchau nach M\u00f6glichkeiten, das Kulturangebot der Gro\u00dfen Kreisstadt zu bereichern, und eine der augenscheinlichsten Probleme war das Fehlen eines Kinos. Nach einem Aufruf in der Zeitung und pers\u00f6nlichen Anfragen, fanden sich einige Glauchauer zum Gespr\u00e4ch im Rathaus ein. Wir setzten uns zusammen und gr\u00fcndeten den Verein. Dabei ging es uns weniger um das Auff\u00fchren gro\u00dfer Hollywood -Produktionen, sondern um den k\u00fcnstlerischen, gewaltfreien und humorvollen Anspruch. Nicht zuletzt sollten auch Kinderfilme ein Bestandteil des Programms sein.<br \/>Nach einigen organisatorischen Anlaufschwierigkeiten fanden wir einen geeigneten Veranstaltungsort und verwarfen ihn zugunsten einer anderen Spielst\u00e4tte wieder. Seit Mitte des Jahres 2005 hatten wir hier eine feste Zusage und unterschrieben im September den Mietvertrag. Durch enge Zusammenarbeit mit Stadt und B\u00fcrgermeister und freundliche Unterst\u00fctzung durch den Kulturraum Zwickauer Raum, konnten die notwendigen Mittel zum Umbau des Raumes bereitgestellt werden. Miete und Nebenkosten waren erst einmal gesichert. Projektoren, Leinwand und Bestuhlung wurden besorgt und installiert. Jede freie Minute wurde genutzt, und so kam es Ende November 2005 zur Er\u00f6ffnungsfeier und ersten Auff\u00fchrung.<br \/>Seitdem liegen mehr als 6 Jahre, unz\u00e4hlige Filme und viele andere Veranstaltungen hinter uns und wir sind inzwischen fester Bestandteil des Glauchauer Kulturangebotes und das soll auch so bleiben.<br \/>Mittlerweile konnten wir uns als eigenst\u00e4ndiger und alternativer Anlaufpunkt f\u00fcr Film- und Kulturinteressierte \u00fcber die Grenzen Glauchaus hinaus etablieren.<br \/>Auch in Zukunft haben wir vor, ein anspruchsvolles Filmerlebnis zu bieten, was sich abseits von Mainstream , Aggressivit\u00e4t und Schnelllebigkeit etabliert. Besonders wichtig ist uns dabei auch weiterhin, dass die Preise f\u00fcr Eintritt und ev. ein Getr\u00e4nk zum Film niedrig bleiben.<br \/>Unsere kleine B\u00fchne wird f\u00fcr Musikveranstaltungen regelm\u00e4\u00dfig genutzt und wartet immer auf junge Bands, die das Programm erweitern oder einfach mal auftreten wollen. Das ist mit Sicherheit ein relativ einfacher Weg, die Stadt und die Gegend mit intelligenter, bezahlbarer Unterhaltung zu bereichern. Die Mitglieder des Club- Kino e.V. sind alle ehrenamtlich t\u00e4tig und sehen sich nicht als Konkurrenz zu den bestehenden, kommerziellen Kinos. Soviel von uns.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7da8807 elementor-widget elementor-widget-heading\" data-id=\"7da8807\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Programm  M\u00e4rz 2026<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2a56dca e-flex e-con-boxed e-con e-parent\" data-id=\"2a56dca\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a6222b6 elementor-widget elementor-widget-text-editor\" data-id=\"a6222b6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<section><div class=\"row\"><div class=\"col-md-12\"><p>Fabula I 27.02. + 03.03.2026<\/p><p>Mit 55 Jahren steht der einfache Kleinstadtganove Jos (Fedja van Huet) am wirklich aller\u00e4u\u00dfersten Rand der Gesellschaft. Die Beziehung zu seiner Tochter scheint irreparabel zerr\u00fcttet, das Vertrauen seiner Frau hat er wohl endg\u00fcltig verloren. Selbst in seinem Freundeskreis erntet er mittlerweile nur noch Spott. Von echter Freundschaft kann also schon gar nicht mehr gesprochen werden. Als dann auch noch ein Drogendeal scheitert, l\u00e4uft Jos\u2018 Fass \u00fcber. Zwar muss er die Folgen des geplatzten Deals irgendwie aus dem Weg r\u00e4umen, aber vor allem will er nun ein f\u00fcr alle Mal ergr\u00fcnden, warum ausgerechnet f\u00fcr ihn alles so sehr schieflaufen muss.<\/p><p>Freitag, 27.02.2026 \u2013 Beginn: 21:00 Uhr<\/p><p>Dienstag, 03.03.2026 \u2013 Beginn: 20:00 Uhr<\/p><p>Einlass ist eine Stunde vor Beginn<br \/>Leider k\u00f6nnen wir f\u00fcr Filmveranstaltungen keine Reservierungen f\u00fcr Karten und\/oder Pl\u00e4tze entgegennehmen!<\/p><hr \/><\/div><\/div><\/section><section><div class=\"row\"><div class=\"col-md-12\"><p>Extrawurst I 06.03. + 10.03.2026<\/p><p>In einem Tennisclub irgendwo in der deutschen Provinz wird das Sommerfest geplant, und unter Heriberts (Hape Kerkeling) strenger Leitung stehen die Vorbereitungen im Mittelpunkt. Als vorgeschlagen wird, f\u00fcr Erol (Fahri Yard\u0131m), das einzige muslimische Clubmitglied, einen separaten Grill zu organisieren, brechen unerwartete Spannungen auf. Was als scheinbar harmlose Diskussion beginnt, weitet sich schnell zu einer Debatte \u00fcber gesellschaftliche und pers\u00f6nliche Konflikte aus. W\u00e4hrend die Gem\u00fcter immer h\u00f6her kochen, steht der Verein schlie\u00dflich kurz vor dem Zerfall.<\/p><p>Freitag, 06.03.2026 \u2013 Beginn: 21:00 Uhr<\/p><p>Dienstag, 10.03.2026 \u2013 Beginn: 20:00 Uhr<\/p><p>Einlass ist eine Stunde vor Beginn<br \/>Leider k\u00f6nnen wir f\u00fcr Filmveranstaltungen keine Reservierungen f\u00fcr Karten und\/oder Pl\u00e4tze entgegennehmen!<\/p><hr \/><\/div><\/div><\/section><section><div class=\"row\"><div class=\"col-md-12\"><p>Kinderfilm I Die drei ??? \u2013 Toteninsel I 07.03.2026<\/p><p>Kaum haben die Sommerferien begonnen, planen Justus (Julius Weckauf), Peter (Nevio Wendt) und Bob (Levi Brandl) einen Roadtrip. Doch bevor sie aufbrechen k\u00f6nnen, bringt ein anonymer Anruf in der Zentrale ihre Pl\u00e4ne ins Wanken: Ein neuer Fall wartet auf die drei Detektive. Ihre Ermittlungen f\u00fchren sie zu einem geheimnisvollen Geheimbund namens Sphinx. Angef\u00fchrt wird die Organisation vom undurchsichtigen Professor Phoenix (Andreas Pietschmann) und dessen Assistenten Olin (Jannik Sch\u00fcmann). Die Gruppe betreibt illegale Ausgrabungen und verkauft geraubte Artefakte gewinnbringend weiter. Schon bald richtet sich der Fokus auf die Vulkaninsel Makatao, die unter dem Namen Toteninsel gef\u00fcrchtet ist. Dort befindet sich eine Grabst\u00e4tte, um die sich d\u00fcstere Legenden ranken \u2013 angeblich soll niemand, der die Insel betritt, je zur\u00fcckkehren. Trotz der Gefahr begibt sich Sphinx auf eine Expedition dorthin. Welche Motive stecken hinter dieser riskanten Unternehmung? Und welche Rolle spielt der einflussreiche Unternehmer Joseph Saito Hadden (Simon Kluth) bei dem Vorhaben?Samstag,<\/p><p>07.03.2026 \u2013 Beginn: 16:00 Uhr<\/p><p>Einlass ist eine halbe Stunde vor Beginn.<br \/>Leider k\u00f6nnen wir f\u00fcr Filmveranstaltungen keine Reservierungen f\u00fcr Karten und\/oder Pl\u00e4tze entgegennehmen!<\/p><hr \/><p>Die progressiven Nostalgiker I 13.03. + 17.03.2026<\/p><p>Michel (Didier Bourdon) und seine Frau H\u00e9l\u00e8ne (Elsa Zylberstein) f\u00fchren ein, nach allen Regeln der Kunst, beschauliches Leben. Er verdingt sich als nicht sonderlich bedeutender Bankangestellter, sie schmei\u00dft den Haushalt \u2013 wie das im Frankreich der 1950er Jahre eben \u00fcblich ist. Doch dieses Jahrzehnt ist f\u00fcr die beiden schneller Geschichte, als geplant. Denn durch einen Kurzschluss setzt die neue Waschmaschine das ganze Haus unter Strom und schickt die beiden irrerweise durch die Zeit bis ins Jahr 2025. F\u00fcr H\u00e9l\u00e8ne entpuppt sich das als regelrechter Befreiungsschlag: Sie muss ihr Dasein nicht l\u00e4nger als Hausfrau fristen, kann Karriere machen und muss den Ton nicht l\u00e4nger nur von ihrem Mann angeben lassen. Doch der kommt wesentlich schlechter mit der neuen Welt zurecht als sie. Aber kann oder sollte die Waschmaschine noch einmal f\u00fcr eine Reise zur\u00fcck angeschmissen werden?<\/p><p>Freitag, 13.03.2026 \u2013 Beginn: 21:00 Uhr<\/p><p>Dienstag, 17.03.2026 \u2013 Beginn: 20:00 Uhr<\/p><p>Einlass ist eine Stunde vor Beginn<br \/>Leider k\u00f6nnen wir f\u00fcr Filmveranstaltungen keine Reservierungen f\u00fcr Karten und\/oder Pl\u00e4tze entgegennehmen!<\/p><hr \/><p>Die \u00c4ltern I 20.03. + 24.03.2026<\/p><p>Die Zeiten, in denen die Leserschaft gar nicht genug von Hannes (Sebastian Bezzel) bekommen konnte und ihm die B\u00fccher f\u00f6rmlich aus der Hand riss, liegen schon ein paar J\u00e4hrchen zur\u00fcck. Doch dem Schriftsteller scheinen auch andere Dinge im Leben zu reichen. So sieht er sich erf\u00fcllt vom eigenen H\u00e4uschen, seiner Frau Sara (Anna Schudt) und den gemeinsamen Kindern Carla (Kya-Celina Barucki) und Nick (Philip M\u00fcller). Aus Hannes\u2018 Perspektive l\u00e4uft also eigentlich alles Rund. Doch wer seine Familie fragt, bekommt nicht nur \u00fcberschw\u00e4nglich positive Antworten zur\u00fcck. Die w\u00fcrden sich n\u00e4mlich manchmal auch einfach nur ein bisschen weniger aufdringliche F\u00fcrsorge W\u00fcnschen. Und altkluge Kommentare von der Seitenlinie braucht auch niemand. Doch Gr\u00fcnde f\u00fcr eine Krise sind das noch nicht. Die kommen erst noch \u2013 n\u00e4mlich, als Hannes\u2018 Romanreihe vom Verlag endg\u00fcltig aus dem Programm genommen wird, Sara eine Beziehungspause verlangt, Nicks schulische Perspektive immer finsterer wird und Carla ausziehen will. Hannes jedoch scheint in alten Mustern festzuh\u00e4ngen. Aber dann lernt er Vanessa (Judith Bohle) kennen, die einiges bei ihm in Bewegung zu bringen scheint\u2026<\/p><p>Freitag, 20.03.2026 \u2013 Beginn: 21:00 Uhr<\/p><p>Dienstag, 24.03.2026 \u2013 Beginn: 20:00 Uhr<\/p><p>Einlass ist eine Stunde vor Beginn<br \/>Leider k\u00f6nnen wir f\u00fcr Filmveranstaltungen keine Reservierungen f\u00fcr Karten und\/oder Pl\u00e4tze entgegennehmen!<\/p><hr \/><p>Dust Bunny I 27.03. + 31.03.2026<\/p><p>Aurora (Sophie Sloan) ist zehn Jahre alt und will sich nichts anderes einreden lassen: Ein Monster hat ihre gesamte Familie verschlungen. Gl\u00fcck im Ungl\u00fcck: Um den Mann von nebenan (Mads Mikkelsen) ranken sich n\u00e4mlich Ger\u00fcchte, dass er mit Monstern jeglicher Couleur kurzen Prozess macht. Die beiden tun sich tats\u00e4chlich zusammen. Jedoch wird schnell klar, dass sie in ziemlich unterschiedlichen Welten leben \u2013 Aurora in der, in der Monster echt sind, und der Nachbar in der, in der er kein Monsterj\u00e4ger, sondern ein kaltbl\u00fctiger Auftragskiller ist. Doch der Durst nach Rache ist es, der die beiden in ihrem Kampf eint.<\/p><p>Freitag, 27.03.2026 \u2013 Beginn: 21:00 Uhr<\/p><p>Dienstag, 31.03.2026 \u2013 Beginn: 20:00 Uhr<\/p><p>Einlass ist eine Stunde vor Beginn<br \/>Leider k\u00f6nnen wir f\u00fcr Filmveranstaltungen keine Reservierungen f\u00fcr Karten und\/oder Pl\u00e4tze entgegennehmen!<\/p><\/div><\/div><\/section><section><\/section>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Anschrift: Clubkino Glauchau e.V. Marienstrasse 46 08371 Glauchau Website: Hier Klicken Telefon: 03763 172975 E-Mail: info@clubkino-glauchau.de Programm: folgt&#8230; \u00dcber Uns Der Verein Clubkino Glauchau e.V. besteht mittlerweile im 7. Jahr. Wer h\u00e4tte 2005, einschlie\u00dflich der Macher, gedacht, dass es uns so lange gibt. Damals suchte die Stadtverwaltung Glauchau nach M\u00f6glichkeiten, das Kulturangebot der Gro\u00dfen Kreisstadt [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1448,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28,36],"tags":[],"class_list":["post-556","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-branchenverzeichnis","category-entertainment-musik"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 19:14:09","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/posts\/556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/comments?post=556"}],"version-history":[{"count":24,"href":"https:\/\/www.neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/posts\/556\/revisions"}],"predecessor-version":[{"id":1942,"href":"https:\/\/www.neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/posts\/556\/revisions\/1942"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/media\/1448"}],"wp:attachment":[{"href":"https:\/\/www.neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/media?parent=556"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/categories?post=556"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/tags?post=556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}