{"id":643,"date":"2025-12-15T12:33:11","date_gmt":"2025-12-15T11:33:11","guid":{"rendered":"http:\/\/neuesmitteldeutschland.test\/?p=643"},"modified":"2026-04-30T11:11:10","modified_gmt":"2026-04-30T09:11:10","slug":"bowlingpub-glauchau","status":"publish","type":"post","link":"https:\/\/www.neues-mitteldeutschland.de\/index.php\/2025\/12\/15\/bowlingpub-glauchau\/","title":{"rendered":"BowlingPub-Glauchau"},"content":{"rendered":"<div id=\"marktplatz_client_view_table\" class=\"row\">\n<div class=\"col-sm-12 col-md-7 col-xs-12\">\n<h1>BowlingPub-Glauchau<\/h1>\n<section id=\"marktplatz_client_view_contact_table\">\n<div id=\"marktplatz_client_view_contact_table_row\" class=\"row\">\n<div class=\"col-sm-4 col-xs-8\">Anschrift<\/div>\n<div class=\"col-sm-8 col-xs-8\">Sachsen Catering Glauchau UG, haftungsbeschr\u00e4nkt<br \/>\nBowling-Pub-Glauchau<br \/>\nG\u00fcterbahnhofstra\u00dfe 608371 Glauchau<\/div>\n<\/div>\n<div id=\"marktplatz_client_view_contact_table_row\" class=\"row\">\n<div class=\"col-sm-4 col-xs-8\">Webseite<\/div>\n<div class=\"col-sm-8 col-xs-8\"><a href=\"http:\/\/www.bowlingpub-glauchau.de\" target=\"_blank\" rel=\"noopener\">www.bowlingpub-glauchau.de <\/a><\/div>\n<\/div>\n<div id=\"marktplatz_client_view_contact_table_row\" class=\"row\">\n<div class=\"col-sm-4 col-xs-8\">Telefon<\/div>\n<div class=\"col-sm-8 col-xs-8\"><a href=\"tel:03763 \/ 48 96 54\">03763 \/ 48 96 54<\/a><\/div>\n<\/div>\n<div id=\"marktplatz_client_view_contact_table_row\" class=\"row\">\n<div class=\"col-sm-4 col-xs-8\">Fax<\/div>\n<div class=\"col-sm-8 col-xs-8\">03763 \/ 48 96 55<\/div>\n<\/div>\n<div id=\"marktplatz_client_view_contact_table_row\" class=\"row\">\n<div class=\"col-sm-4 col-xs-8\">E-Mail<\/div>\n<div class=\"col-sm-8 col-xs-8\"><a href=\"mailto:info@bowlingpub-glauchau.de\">info@bowlingpub-glauchau.de<\/a><\/div>\n<\/div>\n<div id=\"marktplatz_client_view_contact_table_description\" class=\"row\">\n<div class=\"col-sm-12 col-xs-12\">\n<hr \/>\n<section>\n<div class=\"row\">\n<div class=\"col-md-12\">\n<div>\n<p><strong>Unsere \u00d6ffnungszeiten:<\/strong><\/p>\n<section>\n<div class=\"row\">\n<div class=\"col-md-3 col-sm-6 col-xs-12\">Montag<\/div>\n<div class=\"col-md-3 col-sm-6 col-xs-12\">15.00 &#8211; 22.00 Uhr<\/div>\n<div class=\"col-md-3 col-sm-6 col-xs-12\">Dienstag<\/div>\n<div class=\"col-md-3 col-sm-6 col-xs-12\">Ruhetag<\/div>\n<div class=\"col-md-3 col-sm-6 col-xs-12\">Mittwoch<\/div>\n<div class=\"col-md-3 col-sm-6 col-xs-12\">Ruhetag<\/div>\n<div class=\"col-md-3 col-sm-6 col-xs-12\">Donnerstag<\/div>\n<div class=\"col-md-3 col-sm-6 col-xs-12\">15.00 &#8211; 22.00 Uhr<\/div>\n<div class=\"col-md-3 col-sm-6 col-xs-12\">Freitag<\/div>\n<div class=\"col-md-3 col-sm-6 col-xs-12\">15.00 &#8211; 24.00 Uhr<\/div>\n<div class=\"col-md-3 col-sm-6 col-xs-12\">Samstag<\/div>\n<div class=\"col-md-3 col-sm-6 col-xs-12\">15.00 &#8211; 24.00 Uhr<\/div>\n<div class=\"col-md-3 col-sm-6 col-xs-12\">Sonntag<\/div>\n<div class=\"col-md-3 col-sm-6 col-xs-12\">15.00 &#8211; 22.00 Uhr<\/div>\n<div class=\"col-md-3 col-sm-6 col-xs-12\">(Vor)Feiertage<\/div>\n<div class=\"col-md-3 col-sm-6 col-xs-12\">15.00 &#8211; 22.00 Uhr<\/div>\n<\/div>\n<\/section>\n<\/div>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<div class=\"col-sm-12 col-md-5 col-xs-12 map\">\n<div class=\"gdprlock-placeholder gdprlock-placeholder-action\" data-original-width=\"100%\" data-original-height=\"450\" data-original-frameborder=\"1\" data-original-scrolling=\"no\" data-original-marginheight=\"0\" data-original-marginwidth=\"0\" data-original-src=\"https:\/\/maps.google.com\/maps?hl=de&amp;q=G%C3%BCterbahnhofstra%C3%9Fe+6, Glauchau+%28Sachsen+Catering+Glauchau+UG%2C+%28+haftungsbeschr%C3%A4nkt+%29%29%0D%0ABowling-Pub-Glauchau&amp;ie=UTF8&amp;t=m&amp;vpsrc=0&amp;z=16&amp;output=embed\">\n<div class=\"gdprlock-placeholder-text\">Sie m\u00fcssen der Nutzung von Cookies ( Fremdinhalte ) zustimmen, um diesen Inhalt anzuzeigen.<\/div>\n<\/div>\n<p><a href=\"http:\/\/maps.google.com\/maps?daddr=G%C3%BCterbahnhofstra%C3%9Fe+6,08371 Glauchau+%28Sachsen+Catering+Glauchau+UG%2C+%28+haftungsbeschr%C3%A4nkt+%29%29%0D%0ABowling-Pub-Glauchau&amp;ie=UTF8&amp;t=m&amp;vpsrc=0&amp;z=16&amp;source=embed\" target=\"_blank\" rel=\"noopener\">Gr\u00f6\u00dfere Kartenansicht<\/a><\/p>\n<\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"col-md-12 col-sm-12 col-xs-12\">\n<hr \/>\n<\/div>\n<\/div>\n<div id=\"marktplatz_client_view_description\" class=\"row\">\n<div class=\"col-md-12 col-sm-12 col-xs-12\">\n<section>\n<div class=\"row\">\n<div class=\"col-md-12 col-sm-12 col-xs-12\">\n<h2><strong>Das Bowling-Pub Glauchau wurde im Sommer 2011 komplett umgebaut und modernisiert.<\/strong><\/h2>\n<h2><strong>Es bietet Ihnen 10 moderne Bahnen mit ausgereifter Beleuchtung und Schwarzlicht.<\/strong><\/h2>\n<h2><strong>Tradition und neuester Technikstand mit ausgefallenen Designelementen bilden eine perfekt gelungene Symbiose.<\/strong><\/h2>\n<h1><strong>Es erwarten Sie bei uns:<\/strong><\/h1>\n<h2>10 Bahnen mit gepolsterten Sitzgelegenheiten<\/h2>\n<h2>5 Billardtische<\/h2>\n<h2>eine moderne Bar mit gepflegten Drinks, Cocktails, Kaffee-Spezialit\u00e4ten, etc.<\/h2>\n<h2>ein gro\u00dfz\u00fcgiger Gastronomiebereich mit Restaurant (Vollk\u00fcche)<\/h2>\n<h2>wechselnde Programme, Aktionen und Turniere<\/h2>\n<h2>kostenlose Kundenparkpl\u00e4tze<\/h2>\n<\/div>\n<\/div>\n<\/section>\n<hr \/>\n<section>\n<div class=\"row\">\n<div class=\"col-md-4 col-sm-4 col-xs-12\">\n<p><img decoding=\"async\" src=\"https:\/\/neues-mitteldeutschland.de\/images\/marktplatz\/images\/Bowlingpub\/bar1.jpg\" \/><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/neues-mitteldeutschland.de\/images\/marktplatz\/images\/Bowlingpub\/lokal1.jpg\" \/><\/p>\n<\/div>\n<div class=\"col-md-8 col-sm-8 col-xs-12\">\n<h2><u><strong>Sie m\u00f6chten viele Freunde treffen und zu Hause feiern?<\/strong><\/u><\/h2>\n<h3><strong>Wenn da blo\u00df nicht der Stress mit dem Einkaufen und dem ewigen Kochen w\u00e4re!<\/strong><\/h3>\n<h3><strong>Das Bowling Pub Glauchau bietet die perfekte L\u00f6sung f\u00fcr alle Gastgeber:<\/strong><\/h3>\n<h3><strong>Planen Sie Silvester, eine Hochzeit, Geburtstag oder steht ein Familienfest bevor? Erwarten Sie Freunde oder m\u00f6chten gern ein Fest zu Haus das etwas anders ist als sonst? Anstatt teure und zumeist laute und volle Restaurants zu buchen oder aber einen aufwendigen Partyservice zu ordern k\u00f6nnen Sie jetzt ganz neu in Glauchau v\u00f6llig entspannt feiern. Und das ohne die sonst \u00fcblichen Kosten, Verpflichtungen und Stress! Buchen Sie einfach im Bowling Pub Glauchau \u2013 den ersten Qualit\u00e4ts Catering Service f\u00fcr ganze knusprige Spanferkel, ganzes mediterranes Kr\u00e4uterlamm, krachend knusprigen Partyschinken oder aber zart saftigen Riesentruthahn.<br \/>\nAlle Produkte stammen hier aus der Region und werden in unseren Show Grills geliefert. Vor Ihren Augen grillen diese Delikatessen gut sichtbar durch die beleuchtete Glasfront direkt auf Ihrer Terrasse, Garten! Und die Kosten ? unseren Grillspezialit\u00e4ten kann sich jeder leisten ! Unsere Preise starten bei 5,70 inkl Transport \/ Auf . und Abbau von T\u00fcr\/ T\u00fcr. Pro Gast kalkulieren wir ca 500 g reines Fleisch \u2013 das kann kein Restaurant! Die \u00dcberbleibsel aus Ihrem Fest werden zu Ihren eigenen wunderbaren Sandwiches f\u00fcr die n\u00e4chsten Tage!<br \/>\nWir rollen unseren Show Grill direkt auf Ihre Terrasse oder Garten und holen ihn nach dem Essen auch wieder ab , kein Schmutz, kein Benutzen Ihrer K\u00fcche ! Es ist als w\u00e4re nichts geschehen! Decken Sie einfach eine gro\u00dfe mediterrane Tafel und seien Sie Gast auf Ihrem eigenen Fest \u2013 denn unsere Gastgeber legen die F\u00fc\u00dfe hoch!<br \/>\nDie Mindestordergr\u00f6\u00dfe sind 20 Personen \u2013 es war nie einfacher ein gro\u00dfartiges Fest zu kleinen Kosten zu feiern \u2013 ordern Sie heute Ihre Party \u2013 Sie werden uns lieben !<\/strong><\/h3>\n<\/div>\n<\/div>\n<\/section>\n<hr \/>\n<section>\n<div class=\"row\">\n<div class=\"col-md-12\">\n<h1>Besuchen Sie uns doch einmal zu:<\/h1>\n<h2><strong>ALL you can Bowl<\/strong><\/h2>\n<h2><strong>jeden Montag von 15.00 &#8211; 22.00 Uhr f\u00fcr nur 10,80 \u20ac je Stunde<\/strong><\/h2>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>BowlingPub-Glauchau Anschrift Sachsen Catering Glauchau UG, haftungsbeschr\u00e4nkt Bowling-Pub-Glauchau G\u00fcterbahnhofstra\u00dfe 608371 Glauchau Webseite www.bowlingpub-glauchau.de Telefon 03763 \/ 48 96 54 Fax 03763 \/ 48 96 55 E-Mail info@bowlingpub-glauchau.de Unsere \u00d6ffnungszeiten: Montag 15.00 &#8211; 22.00 Uhr Dienstag Ruhetag Mittwoch Ruhetag Donnerstag 15.00 &#8211; 22.00 Uhr Freitag 15.00 &#8211; 24.00 Uhr Samstag 15.00 &#8211; 24.00 Uhr Sonntag 15.00 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2016,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28,52],"tags":[],"class_list":["post-643","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-branchenverzeichnis","category-sport-freizeit"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 12:41:46","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/posts\/643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/comments?post=643"}],"version-history":[{"count":4,"href":"https:\/\/www.neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/posts\/643\/revisions"}],"predecessor-version":[{"id":2017,"href":"https:\/\/www.neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/posts\/643\/revisions\/2017"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/media\/2016"}],"wp:attachment":[{"href":"https:\/\/www.neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/media?parent=643"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/categories?post=643"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/tags?post=643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}